{"id":1273,"date":"2017-06-07T13:03:26","date_gmt":"2017-06-07T13:03:26","guid":{"rendered":"http:\/\/tekkieuni.com\/es\/graduates\/"},"modified":"2019-10-02T08:52:49","modified_gmt":"2019-10-02T08:52:49","slug":"graduates","status":"publish","type":"page","link":"https:\/\/tekkieuni.com\/es\/graduates\/","title":{"rendered":"Graduados"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":31,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-graduates.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-1273","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nuestros graduados: c\u00f3mo comenzaron y en qu\u00e9 se convirtieron<\/title>\n<meta name=\"description\" content=\"Estamos muy orgullosos de nuestros graduados. Escuche las fascinantes historias de ex alumnos que participaron en nuestros diversos programas. Comenzaron con poca o ninguna experiencia en programaci\u00f3n y hoy aspiran a innovadores j\u00f3venes con amplia experiencia pr\u00e1ctica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tekkieuni.com\/es\/graduates\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestros graduados: c\u00f3mo comenzaron y en qu\u00e9 se convirtieron\" \/>\n<meta property=\"og:description\" content=\"Estamos muy orgullosos de nuestros graduados. Escuche las fascinantes historias de ex alumnos que participaron en nuestros diversos programas. Comenzaron con poca o ninguna experiencia en programaci\u00f3n y hoy aspiran a innovadores j\u00f3venes con amplia experiencia pr\u00e1ctica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tekkieuni.com\/es\/graduates\/\" \/>\n<meta property=\"og:site_name\" content=\"TekkieUni - Coding for Kids\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TekkieUni\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-02T08:52:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nuestros graduados: c\u00f3mo comenzaron y en qu\u00e9 se convirtieron","description":"Estamos muy orgullosos de nuestros graduados. Escuche las fascinantes historias de ex alumnos que participaron en nuestros diversos programas. Comenzaron con poca o ninguna experiencia en programaci\u00f3n y hoy aspiran a innovadores j\u00f3venes con amplia experiencia pr\u00e1ctica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tekkieuni.com\/es\/graduates\/","og_locale":"es_ES","og_type":"article","og_title":"Nuestros graduados: c\u00f3mo comenzaron y en qu\u00e9 se convirtieron","og_description":"Estamos muy orgullosos de nuestros graduados. Escuche las fascinantes historias de ex alumnos que participaron en nuestros diversos programas. Comenzaron con poca o ninguna experiencia en programaci\u00f3n y hoy aspiran a innovadores j\u00f3venes con amplia experiencia pr\u00e1ctica.","og_url":"https:\/\/tekkieuni.com\/es\/graduates\/","og_site_name":"TekkieUni - Coding for Kids","article_publisher":"https:\/\/www.facebook.com\/TekkieUni\/","article_modified_time":"2019-10-02T08:52:49+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tekkieuni.com\/es\/graduates\/","url":"https:\/\/tekkieuni.com\/es\/graduates\/","name":"Nuestros graduados: c\u00f3mo comenzaron y en qu\u00e9 se convirtieron","isPartOf":{"@id":"https:\/\/tekkieuni.com\/#website"},"datePublished":"2017-06-07T13:03:26+00:00","dateModified":"2019-10-02T08:52:49+00:00","description":"Estamos muy orgullosos de nuestros graduados. Escuche las fascinantes historias de ex alumnos que participaron en nuestros diversos programas. Comenzaron con poca o ninguna experiencia en programaci\u00f3n y hoy aspiran a innovadores j\u00f3venes con amplia experiencia pr\u00e1ctica.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tekkieuni.com\/es\/graduates\/"]}]},{"@type":"WebSite","@id":"https:\/\/tekkieuni.com\/#website","url":"https:\/\/tekkieuni.com\/","name":"TekkieUni - Coding for Kids","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tekkieuni.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/pages\/1273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/comments?post=1273"}],"version-history":[{"count":0,"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/pages\/1273\/revisions"}],"wp:attachment":[{"href":"https:\/\/tekkieuni.com\/es\/wp-json\/wp\/v2\/media?parent=1273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}